{"id":2011,"date":"2018-08-14T20:37:12","date_gmt":"2018-08-14T18:37:12","guid":{"rendered":"http:\/\/www.adictosaljetlag.com\/?p=2011"},"modified":"2018-11-19T20:31:27","modified_gmt":"2018-11-19T19:31:27","slug":"china-dia-1-vuelo-madrid-pekin-pekin-templo-del-cielo-dashilan","status":"publish","type":"post","link":"https:\/\/www.adictosaljetlag.es\/index.php\/2018\/08\/14\/china-dia-1-vuelo-madrid-pekin-pekin-templo-del-cielo-dashilan\/","title":{"rendered":"China D\u00eda 1: Vuelo Madrid-Pekin \/ Pekin (Templo del cielo, Dashilan)"},"content":{"rendered":"<p>Hemos cogido el vuelo de Madrid a Pek\u00edn con <strong>aeroflot<\/strong> haciendo una peque\u00f1a escala de 1,5 horas en Mosc\u00fa. El primer avi\u00f3n de Madrid a Mosc\u00fa es peque\u00f1o y no tiene pantallas en los asientos, as\u00ed que tienes que llevarte el entretenimiento preparado de casa. Al final el vuelo lleg\u00f3 a Mosc\u00fa con 45 minutos de retraso, y teniendo en cuenta que nuestra escala era de 1:30 h nos toc\u00f3 correr un poco en los controles que hay que cruzar hasta llegar a la puerta de embarque hacia Pekin. Despu\u00e9s de llegar a la puerta de embarque resulta que el vuelo sale de Mosc\u00fa con 1h de retraso&#8230; la parte positiva es que justo al lado hay un bar con enchufes para cargar los m\u00f3viles as\u00ed que pedimos un par de cervezas y esperamos all\u00ed una hora.<\/p>\n<p>Al final llegamos a Pek\u00edn con 1h de retraso: punto negativo para aeroflot, pero lo peor es que nuestras maletas no salen por la cinta: otro <strong>punto muy negativo para aeroflot<\/strong>&#8230; Seg\u00fan comentaron, el avi\u00f3n iba demasiado lleno y nuestras maletas no cab\u00edan as\u00ed que se quedaron en Mosc\u00fa esperando al siguiente vuelo que sal\u00eda esa misma tarde. Hab\u00eda unas 10 personas en la misma situaci\u00f3n, as\u00ed que nos toc\u00f3 esperar otra lenta cola para rellenar el formulario&#8230;\u00a0La buena noticia es que al d\u00eda siguiente por la tarde nos enviar\u00e1n las maletas directamente a nuestro hotel en Pek\u00edn, y la mala noticia es que nos toca estar un d\u00eda entero sin maleta &#x1f622;.<\/p>\n<p>Despu\u00e9s de salir del aeropuerto 2 horas m\u00e1s tarde de lo planeado nos dirigimos al <strong>Airport Express<\/strong>. Para realizar el pago no aceptan tarjeta, pero cerca de la entrada hay un cajero ATM as\u00ed que sacamos dinero. El Airport Express cuesta 25\u00a5 cada billete y en las m\u00e1quinas autom\u00e1ticas no permiten pagar con billetes de 100\u00a5 (que son los billetes que te da el cajero) as\u00ed que hay que pagarlo en la ventanilla, a esperar otra cola&#8230;<\/p>\n<p>Aproximadamente a las 13:00 por fin montamos en el AirPort express. Te puedes bajar en la estaci\u00f3n de\u00a0<em>Sanyuanqiao<\/em>\u00a0o en la de\u00a0<em>Dongzhimen<\/em>\u00a0y en cualquiera de ellas coger un billete de metro hasta tu destino. Nosotros bajamos en\u00a0<em>Dongzhimen<\/em> y en la estaci\u00f3n de metro fuimos a la taquilla a coger dos <strong>IC Card<\/strong> (tambi\u00e9n pod\u00edamos haberlas cogido en la estaci\u00f3n de airport express del aeropuerto). Cada tarjeta cuesta 20\u00a5 de dep\u00f3sito y otros 20\u00a5 m\u00ednimo de recarga (puedes volver a recargar m\u00e1s cuando lo necesites), as\u00ed que en total cuesta 40\u00a5 cada una aunque luego te devuelven 20\u00a5 cuando devuelves la tarjeta. En Pek\u00edn es casi imprescindible coger las IC Card si quieres ahorrarte colas innecesarias en las taquillas si no tienes dinero suelto, y es super c\u00f3modo porque entras directamente por el torno y pasas la tarjeta por el lector y al salir vuelves a pasarla y autom\u00e1ticamente te resta el importe seg\u00fan el trayecto que hayas realizado.<\/p>\n<p>Nuestro hotel es el\u00a0<strong>Park Plaza Beijing Wangfujing<\/strong>\u00a0(101\u20ac la noche) y para rematar la ma\u00f1ana de mala suerte la ubicaci\u00f3n del hotel en google maps es incorrecta as\u00ed que tuvimos que dar varias vueltas hasta que lo conseguimos localizar (En nuestro mapa de Pek\u00edn al final del post hemos indicado la localizaci\u00f3n correcta). Todo tiene su lado bueno, y es que el hotel est\u00e1 mucho mas cerca de la estaci\u00f3n de metro de lo que pens\u00e1bamos as\u00ed que nos viene genial para pasar estos 4 d\u00edas en Pek\u00edn.<\/p>\n<p><span id=\"templo-del-cielo\" class=\"lugar-link\">Y<\/span> por fin a las 15:20 salimos hacia el <strong>Templo del Cielo<\/strong>. Lo que mas nos gust\u00f3 fue nada mas entrar ver a tant\u00edsima gente local congregada la tarde del domingo jugando a las cartas y al xi\u00e0ngq\u00ed (Un juego de mesa chino similar al ajedrez) alrededor del &#8220;<em>Long Corridor<\/em>&#8220;, un largo pasillo de madera que llega hasta el <em>Sal\u00f3n de la Oraci\u00f3n por la Buena Cosecha<\/em>.<\/p>\n<div id=\"attachment_2023\" style=\"width: 570px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/domingoTemploDelCielo_Pekin.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2023\" class=\"wp-image-2023 \" src=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/domingoTemploDelCielo_Pekin-800x566.jpg\" alt=\"\" width=\"560\" height=\"396\" data-wp-pid=\"2023\" \/><\/a><p id=\"caption-attachment-2023\" class=\"wp-caption-text\">Tarde de domingo en el Templo del Cielo<\/p><\/div>\n<p>El complejo es bastante grande y pasamos all\u00ed casi 2 horas, haciendo una parada para comer en uno de los chiringuitos con aire acondicionado que vimos all\u00ed dentro. Pedimos un plato de pollo al curry, mal\u00edsimo como era de esperar, y 2 cervezas.<\/p>\n<p><span id=\"hutong-dajiang\" class=\"lugar-link\">Salimos<\/span> de nuevo por la puerta este del parque y cogimos el metro hasta llegar a la zona de hutongs cercanos a la calle Qianmen. Cruzamos por el <strong>Hutong\u00a0Dajiang<\/strong> que en la parte sur no ten\u00eda otra cosa mas que casas en obras y decenas de obreros por todas partes y en la parte norte ya lo han restaurado y convertido en una turistada pero a\u00fan sin tiendas abiertas. As\u00ed que ahora mismo este hutong no tiene nada de encanto.<\/p>\n<p><span id=\"calle-qianmen\" class=\"lugar-link\">Llegamos<\/span> a la calle <strong>Qianmen<\/strong>, una calle peatonal muy tur\u00edstica y llena de tiendas pero bastante agradable, e hicimos una parada en el KFC. Con el jet lag ya no sabemos si estamos comiendo, cenando o incluso desayunando&#8230; Pedimos unas piezas de pechuga de pollo picante, muy buenos con un toque especiado diferente al que estamos acustumbrados. <span id=\"calle-dashilan\" class=\"lugar-link\">Desde<\/span> Qianmen giramos por la calle <strong>Dashilan<\/strong>, y nos sorprendi\u00f3 gratamente esta zona porque a esas horas hab\u00eda bastante ambiente, unas cuentas tiendas de ropa y varios restaurantes y puestos callejeros para cenar.<\/p>\n<div id=\"attachment_2018\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/calleDashilan_Pekin.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2018\" class=\"size-medium wp-image-2018\" src=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/calleDashilan_Pekin-400x244.jpg\" alt=\"\" width=\"400\" height=\"244\" data-wp-pid=\"2018\" \/><\/a><p id=\"caption-attachment-2018\" class=\"wp-caption-text\">Calle Dashilan<\/p><\/div>\n<p>All\u00ed pedimos unos rollitos del t\u00edpico Pato Pekin\u00e9s, que estaban bastante buenos<\/p>\n<div id=\"attachment_2019\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/comidaCalleDashilan_Pekin.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-2019\" class=\"size-medium wp-image-2019\" src=\"https:\/\/adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/comidaCalleDashilan_Pekin-400x353.jpg\" alt=\"\" width=\"400\" height=\"353\" data-wp-pid=\"2019\" \/><\/a><p id=\"caption-attachment-2019\" class=\"wp-caption-text\">Puesto de comida callejera en Dashilan: Rollitos de Pato Pekin\u00e9s y dumplings<\/p><\/div>\n<p>Volvimos direcci\u00f3n a la plaza Qianmen para coger el metro y de vuelta al hotel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Volamos de Madrid a Pekin haciendo escala en Mosc\u00fa y por la tarde visitamos el Templo del Cielo y la zona de hutongs de Dashilan<\/p>\n","protected":false},"author":1,"featured_media":2017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[3],"tags":[9,186,200],"lugar":[196,197,198,199],"acf":[],"author_meta":{"display_name":"adictos","author_link":"https:\/\/www.adictosaljetlag.es\/index.php\/author\/adictos\/"},"featured_img":"https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-400x160.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.adictosaljetlag.es\/index.php\/category\/viajes\/\" class=\"advgb-post-tax-term\">Viajes<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Viajes<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.adictosaljetlag.es\/index.php\/category\/viajes\/\" class=\"advgb-post-tax-term\">Diario<\/a>","<a href=\"https:\/\/www.adictosaljetlag.es\/index.php\/category\/viajes\/\" class=\"advgb-post-tax-term\">China<\/a>","<a href=\"https:\/\/www.adictosaljetlag.es\/index.php\/category\/viajes\/\" class=\"advgb-post-tax-term\">Pek\u00edn<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Diario<\/span>","<span class=\"advgb-post-tax-term\">China<\/span>","<span class=\"advgb-post-tax-term\">Pek\u00edn<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publicado 8 a\u00f1os hace","modified":"Actualizado 8 a\u00f1os hace"},"absolute_dates":{"created":"Publicado el 14 agosto, 2018","modified":"Actualizado el 19 noviembre, 2018"},"absolute_dates_time":{"created":"Publicado el 14 agosto, 2018 8:37 pm","modified":"Actualizado el 19 noviembre, 2018 8:31 pm"},"featured_img_caption":"Jugando al xi\u00e0ngq\u00ed en el Templo del Cielo (Pekin, China)","series_order":"","rttpg_featured_image_url":{"full":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"landscape":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"portraits":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"thumbnail":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-150x150.jpg",150,150,true],"medium":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-400x160.jpg",400,160,true],"large":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-800x320.jpg",676,270,true],"1536x1536":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",1536,614,false],"2048x2048":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"gg_gallery_thumbnail":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-450x250.jpg",450,250,true],"extra-small":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-188x75.jpg",188,75,true],"post-image-small":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-400x160.jpg",400,160,true],"post-image":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-676x270.jpg",676,270,true],"wpsso-schema-1x1":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"wpsso-schema-4x3":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin.jpg",2000,800,false],"wpsso-schema-16x9":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-1200x675.jpg",1200,675,true],"wpsso-thumbnail":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-1200x628.jpg",1200,628,true],"wpsso-opengraph":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-1200x628.jpg",1200,628,true],"wpsso-tc-summary":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-600x600-cropped.jpg",600,600,true],"wpsso-tc-lrgimg":["https:\/\/www.adictosaljetlag.com\/wp-content\/uploads\/2018\/08\/temploDelCielo2_Pekin-1200x628.jpg",1200,628,true]},"rttpg_author":{"display_name":"adictos","author_link":"https:\/\/www.adictosaljetlag.es\/index.php\/author\/adictos\/"},"rttpg_comment":45,"rttpg_category":"<a href=\"https:\/\/www.adictosaljetlag.es\/index.php\/category\/viajes\/\" rel=\"category tag\">Viajes<\/a>","rttpg_excerpt":"Volamos de Madrid a Pekin haciendo escala en Mosc\u00fa y por la tarde visitamos el Templo del Cielo y la zona de hutongs de Dashilan","_links":{"self":[{"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/posts\/2011"}],"collection":[{"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/comments?post=2011"}],"version-history":[{"count":11,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/posts\/2011\/revisions"}],"predecessor-version":[{"id":2239,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/posts\/2011\/revisions\/2239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/media\/2017"}],"wp:attachment":[{"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/media?parent=2011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/categories?post=2011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/tags?post=2011"},{"taxonomy":"lugar","embeddable":true,"href":"https:\/\/www.adictosaljetlag.es\/index.php\/wp-json\/wp\/v2\/lugar?post=2011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}